{"id":133,"date":"2024-07-10T10:55:51","date_gmt":"2024-07-10T08:55:51","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=133"},"modified":"2025-10-05T09:14:37","modified_gmt":"2025-10-05T07:14:37","slug":"clause-3-how-to-understand-the-definition-of-the-noun-rated-voltage","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/clause-3-how-to-understand-the-definition-of-the-noun-rated-voltage\/","title":{"rendered":"Absatz 3 \u2013 Wie ist die Definition von \u201eNennspannung\u201c zu verstehen"},"content":{"rendered":"<strong>Nennspannung<\/strong>:<br>Spannung, die dem Ger\u00e4t vom Hersteller zugewiesen wurde.<br>\n<br>\nNormalerweise handelt es sich bei dieser Spannung um die Standardnetzspannung f\u00fcr das Land des Zielmarktes zum Zeitpunkt der Produktentwicklung. Sobald der Zielmarkt bestimmt ist, muss der Hersteller das Produkt gem\u00e4\u00df den Anforderungen des Zielmarkts entwerfen. Es ist nicht m\u00f6glich, ein Produkt mit einer Nennspannung von 100 V AC (Eingangsspannung) zu entwickeln, um es in L\u00e4ndern zu verwenden, in denen die Netzspannung 220 V AC betr\u00e4gt. Gleichzeitig ist die Netzspannung in den meisten L\u00e4ndern ein definierter Wert, sodass der Nennspannungswert hier ein separater Wert ist. Die Internationale Elektrotechnische Kommission stellt eine Webseite mit Informationen zu Steckern und Netzspannung f\u00fcr alle L\u00e4nder bereit: <br><a href=\"https:\/\/iectest.iec.ch\/world-plugs\">https:\/\/iectest.iec.ch\/world-plugs<\/a>. Zu Ihrer Information<br>\n<br>\nIn der Norm IEC 60335-1 basieren alle Tests, die erfordern, dass das Produkt mit Strom versorgt wird oder sich im Betriebszustand befindet, auf der Nennspannung. Bei falscher Nennspannung m\u00fcssen alle Pr\u00fcfungen wiederholt werden. Das Labor muss vor der Durchf\u00fchrung der Pr\u00fcfung die Nennspannung ermitteln.<br>\n<br>\nIEC 60335-1 spezifiziert nicht den Wert oder den Bereich der Nennspannung, auf den die Nennspannung eingestellt werden sollte, aber der Bereich der Nennspannungen wird im ersten Absatz von Abschnitt 1 tats\u00e4chlich als Referenz angegeben, was nicht der Fall ist 250 V f\u00fcr einphasige Ger\u00e4te und 480 V f\u00fcr dreiphasige Ger\u00e4te und andere Stromversorgungsarten \u00fcberschreiten. Im Allgemeinen werden die Nennspannungen diesen Bereich nicht \u00fcberschreiten.<br>Es ist wichtig zu beachten, dass jedes Land seine eigenen Abweichungen basierend auf der Norm IEC 60335-1 hinzuf\u00fcgt und dass diese Abweichungen im Allgemeinen die Anforderungen an die Nennspannung erh\u00f6hen. Zum Beispiel 100 V in Japan, 240 V in Gro\u00dfbritannien und 220 V in China.<br>\n<br>\nEs gibt eine Entscheidung PDSH 2235 f\u00fcr ein Batterieladeger\u00e4t der Klasse I, das mit einer Nennversorgung von 3 N~ und einer Nennspannung von 400 V gekennzeichnet ist. <br>Liegt dieses Batterieladeger\u00e4t im Hinblick auf die angegebene Nennspannungsgrenze von nicht mehr als 250 V im Geltungsbereich von IEC 60335-2-29:2016?<br>Mit Entscheidung beantwortet: Gem\u00e4\u00df dem Geltungsbereich der Norm f\u00e4llt ein Batterieladeger\u00e4t mit einer Nennspannung von 400 V (3N~) nicht unter IEC 60335-2-29.<br>","protected":false},"excerpt":{"rendered":"<p>Nennspannung:Spannung, die dem Ger\u00e4t vom Hersteller zugewiesen wurde. Normalerweise handelt es sich bei dieser Spannung um die Standardnetzspannung f\u00fcr das Land des Zielmarktes zum Zeitpunkt der Produktentwicklung. Sobald der Zielmarkt bestimmt ist, muss der Hersteller das Produkt gem\u00e4\u00df den Anforderungen des Zielmarkts entwerfen. Es ist nicht m\u00f6glich, ein Produkt mit einer Nennspannung von 100 V&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[56],"class_list":["post-133","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-voltage-assigned-to-the-appliance-by-the-manufacturer"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":38,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/133\/revisions"}],"predecessor-version":[{"id":2840,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/133\/revisions\/2840"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}