{"id":162,"date":"2024-07-12T17:56:14","date_gmt":"2024-07-12T15:56:14","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=162"},"modified":"2025-10-05T09:12:48","modified_gmt":"2025-10-05T07:12:48","slug":"clause-3-how-to-understand-the-definition-of-the-noun-rated-power-input","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/clause-3-how-to-understand-the-definition-of-the-noun-rated-power-input\/","title":{"rendered":"Abschnitt 3 \u2013 Wie ist die Definition von \u201eNennleistungsaufnahme\u201c zu verstehen"},"content":{"rendered":"<strong>Nennleistungsaufnahme:<br><\/strong>Leistungsaufnahme, die dem Ger\u00e4t vom Hersteller zugewiesen wurde<br>Anmerkung 1 zum Begriff: Wenn dem Ger\u00e4t keine Leistungsaufnahme zugewiesen ist, ist die Nennleistungsaufnahme f\u00fcr Heizger\u00e4te und kombinierte Ger\u00e4te die Leistungsaufnahme, die gemessen wird, wenn das Ger\u00e4t mit Nennspannung versorgt und im Normalbetrieb betrieben wird.<br>\n<br>\nIm Allgemeinen kann der Hersteller die Nennleistungsaufnahme auf der Eingangsleistung basieren, die von einem Produkt erzeugt wird, das mit seiner Nennspannung unter Bedingungen maximaler Leistungsaufnahme betrieben wird. Dies liegt daran, dass der Leistungseingangstest in Abschnitt 10 erfordert, dass das Produkt mit der Nennspannung betrieben wird. F\u00fcr einige Produkte gibt es m\u00f6glicherweise Sonderf\u00e4lle, die in den folgenden Kapiteln erw\u00e4hnt werden.<br>\n<br>\nF\u00fcr erfahrene Entwicklungsteams wird die Nennleistungsaufnahme in der fr\u00fchen Phase des Produktdesigns festgelegt und die Entwickler entwerfen das Produkt gem\u00e4\u00df dem Designprogramm. Es gibt auch F\u00e4lle, in denen die Entwickler kein Designschema haben und die Nennleistungsaufnahme dann vor\u00fcbergehend best\u00e4tigen, nachdem der Produktprototyp hergestellt wurde. Wenn die Nennspannung eines Raumheizger\u00e4ts (Quarzrohrheizger\u00e4t) beispielsweise 220 V AC betr\u00e4gt, k\u00f6nnen Sie das Produkt normalerweise an eine 220 V-Wechselstromversorgung anschlie\u00dfen , m\u00fcssen Sie auch einschalten), das die tats\u00e4chliche Eingangsleistung, den Wert der Rundung, als Nennleistungsaufnahme aufzeichnet. Wenn daher bei der Durchf\u00fchrung des Leistungseingangstests gem\u00e4\u00df Abschnitt 10 der Pr\u00fcfwert und der Nennwert den in der Norm angegebenen Abweichungsbereich \u00fcberschreiten, kann der Nennleistungseingang ge\u00e4ndert werden, um den Anforderungen von Abschnitt 10 zu entsprechen.<br>\n<br>\nIn den meisten F\u00e4llen wird dem Ger\u00e4t eine Nennleistungsaufnahme zugewiesen. Manchmal wird dem Produkt nur ein Nenneingangsstrom zugewiesen, aber w\u00e4hrend der eigentlichen Pr\u00fcfung verlangen Normen, dass der Betriebszustand des Produkts auf der Grundlage der Nenneingangsleistung bestimmt wird. Anschlie\u00dfend ist es m\u00f6glich, die Angaben zur Eingangsleistung anhand der Informationen in diesem Hinweis zu ermitteln. Dies ist eine seltene Situation. Wenn die Testbedingungen eines Produkts auf der Nenneingangsleistung basieren sollen, wird das Produkt normalerweise mit der Nenneingangsleistung gekennzeichnet. Auch wenn der Hersteller des Produkts keine Nenneingangsleistung angibt, wird ein externes Testlabor beim Testen des Produkts in der Regel die Angaben zur Eingangsleistung anfordern.<br>Hier ist ein hypothetisches Beispiel einer Quarzrohr-Raumheizung, die mit einer Nennspannung von 220 V AC und einer Nennstromaufnahme von 10 A gekennzeichnet ist, ohne Nennleistungsaufnahme. Bei der Durchf\u00fchrung des W\u00e4rmetests in Abschnitt 11 verlangt die Norm, dass das Produkt mit der 1,15-fachen Nenneingangsleistung betrieben wird. In diesem Fall kann die Nennleistungsaufnahme mithilfe der Informationen in den Anmerkungen zu diesem Artikel ermittelt werden.<br>Heizger\u00e4te weisen normalerweise eine Nennleistungsaufnahme auf.<br>","protected":false},"excerpt":{"rendered":"<p>Nennleistungsaufnahme:Leistungsaufnahme, die dem Ger\u00e4t vom Hersteller zugewiesen wurdeAnmerkung 1 zum Begriff: Wenn dem Ger\u00e4t keine Leistungsaufnahme zugewiesen ist, ist die Nennleistungsaufnahme f\u00fcr Heizger\u00e4te und kombinierte Ger\u00e4te die Leistungsaufnahme, die gemessen wird, wenn das Ger\u00e4t mit Nennspannung versorgt und im Normalbetrieb betrieben wird. Im Allgemeinen kann der Hersteller die Nennleistungsaufnahme auf der Eingangsleistung basieren, die von&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[152,59,56],"class_list":["post-162","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-rated-cu","tag-power-input-assigned-to-the-appliance-by-the-manufacturer","tag-voltage-assigned-to-the-appliance-by-the-manufacturer"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=162"}],"version-history":[{"count":30,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/162\/revisions"}],"predecessor-version":[{"id":2838,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/162\/revisions\/2838"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}