{"id":207,"date":"2024-07-14T16:55:00","date_gmt":"2024-07-14T14:55:00","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=207"},"modified":"2025-09-27T17:50:25","modified_gmt":"2025-09-27T15:50:25","slug":"clause-3-how-to-understand-the-definition-of-rated-frequency-range","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/clause-3-how-to-understand-the-definition-of-rated-frequency-range\/","title":{"rendered":"Abschnitt 3 \u2013 Wie ist die Definition des \u201eNennfrequenzbereichs\u201c zu verstehen"},"content":{"rendered":"Nennfrequenzbereich: vom Hersteller dem Ger\u00e4t zugewiesener Frequenzbereich, ausgedr\u00fcckt durch seine Unter- und Obergrenzen.<br>\n<br>\nDie Nennfrequenz in Form eines Bereichs, im Allgemeinen 50\u201360 Hz, aber alle L\u00e4nder der Welt haben entweder eine Netzfrequenz von 50 Hz oder 60 Hz, es gibt keinen Zwischenfrequenzwert, daher ist die Definition nicht sehr aussagekr\u00e4ftig. Allerdings gibt es immer noch K\u00e4ufer bzw. Hersteller, die den Frequenzbereich in Form von 50-60Hz angeben. Selbst um die durch die instabile Netzspannung verursachten Frequenzschwankungen zu ber\u00fccksichtigen, ber\u00fccksichtigt 50\u201360 Hz meiner Meinung nach nicht die Situation von weniger als 50 Hz oder mehr als 60 Hz.<br>Daher empfehle ich, die Nennfrequenz direkt als 50\/60Hz zu kennzeichnen.<br>","protected":false},"excerpt":{"rendered":"<p>Nennfrequenzbereich: vom Hersteller dem Ger\u00e4t zugewiesener Frequenzbereich, ausgedr\u00fcckt durch seine Unter- und Obergrenzen. Die Nennfrequenz in Form eines Bereichs, im Allgemeinen 50\u201360 Hz, aber alle L\u00e4nder der Welt haben entweder eine Netzfrequenz von 50 Hz oder 60 Hz, es gibt keinen Zwischenfrequenzwert, daher ist die Definition nicht sehr aussagekr\u00e4ftig. Allerdings gibt es immer noch K\u00e4ufer&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[62,63],"class_list":["post-207","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-frequency-assigned-to-the-appliance-by-the-manufacturer","tag-frequency-range-assigned-to-the-appliance-by-the-manufacturer-expressed-by-its-lower-and-upper-limits"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":19,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":1169,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/207\/revisions\/1169"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}