{"id":2257,"date":"2024-09-04T17:27:41","date_gmt":"2024-09-04T15:27:41","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=2257"},"modified":"2025-09-27T17:50:23","modified_gmt":"2025-09-27T15:50:23","slug":"clause-3-how-to-understand-the-definition-of-extra-low-voltage","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/clause-3-how-to-understand-the-definition-of-extra-low-voltage\/","title":{"rendered":"Abschnitt 3 \u2013 Wie ist die Definition von \u201eKleinspannung\u201c zu verstehen"},"content":{"rendered":"Kleinspannung: Von einer Quelle innerhalb des Ger\u00e4ts gelieferte Spannung, die 50 V zwischen Leitern und zwischen Leitern und Erde nicht \u00fcberschreitet, wenn das Ger\u00e4t mit Nennspannung versorgt wird<br>\n<br>\nGem\u00e4\u00df der Definition der EU-Niederspannungsrichtlinie reicht die Niederspannung von 50\u20131000 V f\u00fcr Wechselstrom und 75\u20131500 V f\u00fcr Gleichstrom. \u00dcbrigens teilen die meisten L\u00e4nder Hoch- und Niederspannung nach diesem Spannungswert auf. Daher handelt es sich bei Spannungen \u00fcber der Obergrenze des Bereichs um Hochspannungen und bei Spannungen unterhalb der Untergrenze des Bereichs um Kleinspannungen. Die Definition hier in der Norm unterscheidet nicht zwischen Gleich- und Wechselstrom. Bitte beachten Sie, dass hier nur ein Spannungsname entsprechend dem Spannungswert definiert wird und nicht ein bestimmter Teil des Niederspannungskreises definiert wird. Da die Spannung relativ ist, muss beim Messen der Spannung die Spannung zwischen den beiden Enden gemessen werden, d. h. die Spannung muss einen Referenzpunkt haben, daher erw\u00e4hnt die Norm die Spannung zwischen den Dr\u00e4hten und zwischen den Dr\u00e4hten und der Erde.<br>\n<br>\nDie Ausgangsspannung gew\u00f6hnlicher Haushalts-Alkalibatterien, die Arbeitsspannung des Niederspannungskreises nach dem Transformator oder die RC-Abw\u00e4rtsschaltung auf der Steuerplatine gew\u00f6hnlicher Haushaltsger\u00e4te, die alle als Kleinspannung definiert werden k\u00f6nnen .<br>\n<br>\nWie in der Abbildung unten gezeigt, erf\u00fcllen R1 und C1 eine Spannungsreduzierungsfunktion, sodass der Schaltkreis nach R1 und C1 als Kleinspannungsschaltkreis definiert werden kann.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"688\" height=\"226\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/RC-step-down-circuit-ELV.jpg\" alt=\"\" class=\"wp-image-2261\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/RC-step-down-circuit-ELV.jpg 688w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/RC-step-down-circuit-ELV-300x99.jpg 300w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><br>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Kleinspannung: Von einer Quelle innerhalb des Ger\u00e4ts gelieferte Spannung, die 50 V zwischen Leitern und zwischen Leitern und Erde nicht \u00fcberschreitet, wenn das Ger\u00e4t mit Nennspannung versorgt wird Gem\u00e4\u00df der Definition der EU-Niederspannungsrichtlinie reicht die Niederspannung von 50\u20131000 V f\u00fcr Wechselstrom und 75\u20131500 V f\u00fcr Gleichstrom. \u00dcbrigens teilen die meisten L\u00e4nder Hoch- und Niederspannung nach&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[159,89],"class_list":["post-2257","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-earthing","tag-voltage-supplied-from-a-source-within-the-appliance-that-does-not-exceed-50-v-between-conductors-and-between-conductors-and-earth-or-functional-earth-when-the-appliance-is-supplied-at-rated-voltage"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/2257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=2257"}],"version-history":[{"count":20,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/2257\/revisions"}],"predecessor-version":[{"id":2280,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/2257\/revisions\/2280"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=2257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=2257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=2257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}