{"id":227,"date":"2024-07-16T16:50:24","date_gmt":"2024-07-16T14:50:24","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=227"},"modified":"2025-09-27T17:50:25","modified_gmt":"2025-09-27T15:50:25","slug":"clause-3-how-to-understand-the-definition-of-dangerous-malfunction","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/clause-3-how-to-understand-the-definition-of-dangerous-malfunction\/","title":{"rendered":"Absatz 3 \u2013 Wie ist die Definition einer \u201egef\u00e4hrlichen Fehlfunktion\u201c zu verstehen"},"content":{"rendered":"Gef\u00e4hrliche Fehlfunktion: unbeabsichtigter Betrieb des Ger\u00e4ts, der die Sicherheit beeintr\u00e4chtigen kann.<br>\n<br>\nDas Ger\u00e4t selbst funktioniert nicht wie angegeben und kann die Sicherheit gef\u00e4hrden. Beispielsweise bei L\u00fcftern ist der Anlaufkondensator des internen Wechselstrom-Asynchronmotors in Form eines Kurzschlusses oder einer Unterbrechung ausgefallen; Bei Klimaanlagen war der Auslass des innenseitigen Abflussrohrs verstopft, was dazu f\u00fchrte, dass das Wasser nicht abflie\u00dfen konnte und es zu einem \u00dcberlaufen des Wassers kam.<br>\n<br>\nDer entscheidende Punkt hierbei ist, den \u201eunbeabsichtigten Betrieb\u201c zu verstehen. Das Antonym von \u201eunbeabsichtigt\u201c ist \u201ebeabsichtigt\u201c. Im Allgemeinen gibt es in der Norm keine Anforderung f\u00fcr den \u201ebestimmungsgem\u00e4\u00dfen Betrieb\u201c.<br>Hier, lassen Sie mich Ihnen ein schreckliches Beispiel geben. Wenn jemand ein elektrisches B\u00fcgeleisen verwendet, um den Kopf einer anderen Person zu schlagen, verlangt die Norm nicht, dass wir den Kopf der Person nicht verletzen d\u00fcrfen, selbst wenn wir das elektrische B\u00fcgeleisen verwenden.<br>","protected":false},"excerpt":{"rendered":"<p>Gef\u00e4hrliche Fehlfunktion: unbeabsichtigter Betrieb des Ger\u00e4ts, der die Sicherheit beeintr\u00e4chtigen kann. Das Ger\u00e4t selbst funktioniert nicht wie angegeben und kann die Sicherheit gef\u00e4hrden. Beispielsweise bei L\u00fcftern ist der Anlaufkondensator des internen Wechselstrom-Asynchronmotors in Form eines Kurzschlusses oder einer Unterbrechung ausgefallen; Bei Klimaanlagen war der Auslass des innenseitigen Abflussrohrs verstopft, was dazu f\u00fchrte, dass das Wasser&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[66],"class_list":["post-227","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-unintended-operation-of-the-appliance-that-may-impair-safety-copyright-international"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=227"}],"version-history":[{"count":25,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/227\/revisions"}],"predecessor-version":[{"id":1856,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/227\/revisions\/1856"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}