{"id":313,"date":"2024-08-03T05:32:54","date_gmt":"2024-08-03T03:32:54","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=313"},"modified":"2025-09-27T17:50:24","modified_gmt":"2025-09-27T15:50:24","slug":"clause-3-how-to-understand-the-definition-of-type-x-type-y-type-z-attachment","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/clause-3-how-to-understand-the-definition-of-type-x-type-y-type-z-attachment\/","title":{"rendered":"Abschnitt 3 \u2013 So verstehen Sie die Definition von \u201eTyp-X-, Typ-Y-, Typ-Z-Anhang\u201c"},"content":{"rendered":"Die Art des Anschlusses wird vom Hersteller des Ger\u00e4tes festgelegt. Im Allgemeinen wird es selten als Typ X definiert, da dies unn\u00f6tige Risiken f\u00fcr den Hersteller mit sich bringt. Im Allgemeinen wird es als Typ Y definiert. Wenn das Netzkabel vergossen ist, wird es nat\u00fcrlich im Allgemeinen als Typ Z definiert. Die folgende Abbildung listet die Anschlussdiagramme der drei Befestigungsarten auf.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"309\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ.png\" alt=\"\" class=\"wp-image-314\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ.png 355w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ-300x261.png 300w\" sizes=\"auto, (max-width: 355px) 100vw, 355px\" \/><br>\n<\/figure><br>\nAnschluss Typ X: Der Anschluss des Netzkabels erfolgt an einem speziell daf\u00fcr vorgesehenen Platz im Ger\u00e4t. Daher werden beim Ersetzen des Netzkabels keine anderen Teile au\u00dfer der Klemmenleiste und dem internen Kabel ber\u00fchrt. Die Schrauben, mit denen das Netzkabel befestigt wird, sind gew\u00f6hnliche Kreuz- oder Flachkopfschrauben. Der Austausch des Netzkabels erfolgt in einem kontrollierbaren Bereich. Das von normalen Benutzern ersetzte Netzkabel ist relativ einfach und bedienbar.<br>\n<br>\nTyp-Y-Befestigung: Beim Austausch des Netzkabels ist es im Allgemeinen erforderlich, das Strukturgeh\u00e4use des Ger\u00e4ts zu \u00f6ffnen, und diese Geh\u00e4use werden mit speziellen Schrauben, wie z. B. Sechskantschrauben, befestigt. Nach dem \u00d6ffnen des Geh\u00e4uses des Ger\u00e4ts kann der Austauscher die gef\u00e4hrlichen beweglichen Teile oder andere spannungsf\u00fchrende Teile im Inneren des Ger\u00e4ts ber\u00fchren. In diesem Fall ist es sicherer, den Anschluss als Typ-Y-Anschluss zu definieren und das Netzkabel von einem Fachmann austauschen zu lassen. Normalerweise handelt es sich bei den Befestigungsschrauben um normale Schrauben, die von normalen Benutzern bedient werden k\u00f6nnen. Wenn beim Austausch des Netzkabels jedoch gef\u00e4hrliche Teile ber\u00fchrt werden k\u00f6nnen, handelt es sich im Allgemeinen um eine Typ-Y-Befestigung.<br>\n<br>\nAnhang vom Typ Z, siehe Erkl\u00e4rung und Beispiele in 3.2.6.<br>","protected":false},"excerpt":{"rendered":"<p>Die Art des Anschlusses wird vom Hersteller des Ger\u00e4tes festgelegt. Im Allgemeinen wird es selten als Typ X definiert, da dies unn\u00f6tige Risiken f\u00fcr den Hersteller mit sich bringt. Im Allgemeinen wird es als Typ Y definiert. Wenn das Netzkabel vergossen ist, wird es nat\u00fcrlich im Allgemeinen als Typ Z definiert. Die folgende Abbildung listet&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[70,71,72,73],"class_list":["post-313","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-flexible-cord-for-supply-purposes-that-is-fixed-to-the-appliance","tag-method-of-attachment-of-the-supply-cord-such-that-it-can-easily-be-replaced","tag-method-of-attachment-of-the-supply-cord-such-that-any-replacement-is-intended-to-be-made-by-the-manufacturer-its-service-agent-or-similar-qualified-person","tag-method-of-attachment-of-the-supply-cord-such-that-it-cannot-be-replaced-without-breaking-or-destroying-the-appliance"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":22,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/313\/revisions\/1948"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}