{"id":37,"date":"2024-06-21T03:58:42","date_gmt":"2024-06-21T01:58:42","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=37"},"modified":"2025-09-27T17:50:26","modified_gmt":"2025-09-27T15:50:26","slug":"temperature-rises-of-windings-are-determined-by-the-resistance-method","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/temperature-rises-of-windings-are-determined-by-the-resistance-method\/","title":{"rendered":"Temperaturanstiege von Wicklungen werden mit der Widerstandsmethode bestimmt"},"content":{"rendered":"Standard geben Sie uns eine Formel wie folgt:<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"587\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-1024x587.png\" alt=\"\" class=\"wp-image-38\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-1024x587.png 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-300x172.png 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-768x440.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-1536x881.png 1536w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-2048x1174.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure><br>\nDie zentrale Anforderung im Hinweis: Der Widerstand von Wicklungen am Ende der Pr\u00fcfung kann bestimmt werden, indem m\u00f6glichst bald nach dem Ausschalten und dann in kurzen Zeitabst\u00e4nden Widerstandsmessungen durchgef\u00fchrt werden, sodass zur Ermittlung eine Widerstandskurve \u00fcber der Zeit erstellt werden kann Widerstand im Moment des Ausschaltens.<br>\n<br>\nUm die Berechnung zu vereinfachen, habe ich eine Programmdatei f\u00fcr die Berechnung mithilfe einer Excel-Tabelle plus VBA erstellt. Das Formular kann automatisch eine angepasste Kurve entsprechend dem Eingangswiderstandswert und dem entsprechenden Zeitpunkt (Zeitintervall) zeichnen. Die Standardgleichung der angepassten Kurve ist eine quadratische Gleichung. Doppelklicken Sie auf die Kurve, um die angepasste Gleichung zu ersetzen. Die Schnittstelle des Formulars ist unten dargestellt:<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"1024\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-table-697x1024.png\" alt=\"\" class=\"wp-image-40\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-table-697x1024.png 697w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-table-204x300.png 204w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-table-768x1128.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-table-1046x1536.png 1046w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Temperature-rises-of-windings-are-determined-by-the-resistance-method-table-1395x2048.png 1395w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" \/><br>\n<\/figure><br>\nDer Tabellenkopf und die Zellen mit gelbem Hintergrund sind die Zellen, deren Inhalt ge\u00e4ndert werden kann. Nach Eingabe des Widerstandswertes berechnet und tr\u00e4gt das Programm automatisch den Zeitwert entsprechend dem zuvor eingegebenen Zeitintervallwert ein. Au\u00dferdem gibt es in der Tabelle viele Men\u00fczellen, die das Ausf\u00fcllen und Drucken erleichtern.<br>\n<strong><a href=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/06\/Resistance-method-form.xlsm\">Datei herunterladen<\/a><\/strong>","protected":false},"excerpt":{"rendered":"<p>Standard geben Sie uns eine Formel wie folgt: Die zentrale Anforderung im Hinweis: Der Widerstand von Wicklungen am Ende der Pr\u00fcfung kann bestimmt werden, indem m\u00f6glichst bald nach dem Ausschalten und dann in kurzen Zeitabst\u00e4nden Widerstandsmessungen durchgef\u00fchrt werden, sodass zur Ermittlung eine Widerstandskurve \u00fcber der Zeit erstellt werden kann Widerstand im Moment des Ausschaltens. Um&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[13],"tags":[148,149],"class_list":["post-37","post","type-post","status-publish","format-standard","hentry","category-heating","tag-resistance-method","tag-winding"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":29,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":1679,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/37\/revisions\/1679"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}