{"id":90,"date":"2024-07-01T18:03:13","date_gmt":"2024-07-01T16:03:13","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=90"},"modified":"2025-09-27T17:50:26","modified_gmt":"2025-09-27T15:50:26","slug":"how-to-understand-the-ninth-paragraph-of-introduction","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/de\/how-to-understand-the-ninth-paragraph-of-introduction\/","title":{"rendered":"So verstehen Sie den neunten Absatz der EINF\u00dcHRUNG"},"content":{"rendered":"Der neunte Absatz der Einleitung wie folgt:<br>Ein Ger\u00e4t, bei dem Materialien verwendet werden oder deren Konstruktionsformen sich von den in den Anforderungen dieser Norm beschriebenen unterscheiden, kann gem\u00e4\u00df dem Zweck der Anforderungen untersucht und getestet werden und, wenn festgestellt wird, dass sie im Wesentlichen gleichwertig sind, kann davon ausgegangen werden, dass sie der Norm entsprechen. <br>\n<br>\nDa \u200b\u200bdie Norm hinter dem Produkt zur\u00fcckbleibt, verf\u00fcgt das anwendbare Material oder die Struktur im Produkt m\u00f6glicherweise nicht \u00fcber eine entsprechende Klausel oder Anforderung. In diesem Fall kann die Absicht der Norm zur Bestimmung und Pr\u00fcfung herangezogen werden. Beispielsweise kann das Prinzip des doppelten Schutzes zur Bestimmung verwendet werden, ebenso wie das Prinzip des einmaligen Vers\u00e4umnisses, anormale Tests durchzuf\u00fchren; und dann entscheiden, ob die Standardanforderungen eingehalten werden sollen. F\u00fcr Anf\u00e4nger ist es nat\u00fcrlich schwierig, den Grad zu erfassen. Es wird empfohlen, mehr Leute zur Diskussion zu bitten oder leitende Ingenieure um Rat zu bitten, wenn sie die entsprechende Bewertung vornehmen.<br>\n<br>\nIch pers\u00f6nlich denke, dass dies der wichtigste Satz im Abschnitt EINF\u00dcHRUNG ist. Wenn es uns schwerf\u00e4llt, zu entscheiden, ob wir die Anforderungen durchsetzen werden, oder wenn wir uns nicht \u00fcber die Schwere der Durchsetzung der Standards entscheiden k\u00f6nnen. Wir m\u00fcssen \u00fcber die \u201eIntention der Anforderungen\u201c nachdenken. Sie werden feststellen, dass die Anforderungen in der Norm von den tats\u00e4chlichen Nutzungsbedingungen des Produkts sowie angemessenen Missbrauchsbedingungen abgeleitet sind, und Sie m\u00fcssen davon ausgehen, dass eine Anforderung in der Norm diese Nutzungsbedingungen oder angemessenen Missbrauchsbedingungen modelliert . Ich denke, man erh\u00e4lt dann eine relativ vern\u00fcnftige Implementierungsmethode.<br>","protected":false},"excerpt":{"rendered":"<p>Der neunte Absatz der Einleitung wie folgt:Ein Ger\u00e4t, bei dem Materialien verwendet werden oder deren Konstruktionsformen sich von den in den Anforderungen dieser Norm beschriebenen unterscheiden, kann gem\u00e4\u00df dem Zweck der Anforderungen untersucht und getestet werden und, wenn festgestellt wird, dass sie im Wesentlichen gleichwertig sind, kann davon ausgegangen werden, dass sie der Norm entsprechen&#8230;.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[146],"tags":[150],"class_list":["post-90","post","type-post","status-publish","format-standard","hentry","category-introduction","tag-general-information"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"de","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":30,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"predecessor-version":[{"id":1765,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/posts\/90\/revisions\/1765"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/de\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}