{"id":84,"date":"2024-07-01T17:41:36","date_gmt":"2024-07-01T15:41:36","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=84"},"modified":"2025-09-27T17:50:26","modified_gmt":"2025-09-27T15:50:26","slug":"how-to-understand-the-seventh-paragraph-of-introduction","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/es\/how-to-understand-the-seventh-paragraph-of-introduction\/","title":{"rendered":"C\u00f3mo entender el s\u00e9ptimo p\u00e1rrafo de INTRODUCCI\u00d3N"},"content":{"rendered":"El s\u00e9ptimo p\u00e1rrafo de la introducci\u00f3n es el siguiente:<br>Es posible que cada pa\u00eds desee considerar la aplicaci\u00f3n de la norma, en la medida de lo razonable, a aparatos no mencionados en la parte 2 y a aparatos dise\u00f1ados seg\u00fan nuevos principios. En este caso se debe considerar definir el funcionamiento normal, especificando la clasificaci\u00f3n del aparato de acuerdo con la Cl\u00e1usula 6 y especificando si el aparato se utiliza con o sin supervisi\u00f3n. Tambi\u00e9n se deben tener en cuenta categor\u00edas particulares de posibles usuarios y riesgos espec\u00edficos relacionados, como el acceso a piezas vivas, superficies calientes o piezas m\u00f3viles peligrosas.<br>\n<br>\nDebido a que las normas generalmente van a la zaga de la tecnolog\u00eda, puede surgir un nuevo producto para el cual no se han establecido normas para evaluar el producto, en cuyo caso la primera parte de las normas generalmente se puede utilizar para evaluar el producto. En este caso, a\u00fan es necesario categorizar y definir el producto de acuerdo con las normas, incluyendo la consideraci\u00f3n del uso de la poblaci\u00f3n, etc., lo que significa que el producto ser\u00e1 evaluado de manera similar a los productos convencionales.<br>Los productos deben evaluarse en cinco \u00e1reas: protecci\u00f3n contra el riesgo de descarga el\u00e9ctrica, protecci\u00f3n contra el contacto con piezas m\u00f3viles, protecci\u00f3n contra lesiones t\u00e9rmicas, protecci\u00f3n contra el riesgo de incendio y protecci\u00f3n contra el riesgo de sustancias qu\u00edmicas y radiaci\u00f3n.<br>","protected":false},"excerpt":{"rendered":"<p>El s\u00e9ptimo p\u00e1rrafo de la introducci\u00f3n es el siguiente:Es posible que cada pa\u00eds desee considerar la aplicaci\u00f3n de la norma, en la medida de lo razonable, a aparatos no mencionados en la parte 2 y a aparatos dise\u00f1ados seg\u00fan nuevos principios. En este caso se debe considerar definir el funcionamiento normal, especificando la clasificaci\u00f3n del&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[146],"tags":[150],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-introduction","tag-general-information"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"es","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":20,"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"predecessor-version":[{"id":2866,"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/posts\/84\/revisions\/2866"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/es\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}