{"id":266,"date":"2024-07-29T16:45:00","date_gmt":"2024-07-29T14:45:00","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=266"},"modified":"2025-09-27T17:50:25","modified_gmt":"2025-09-27T15:50:25","slug":"clause-3-how-to-understand-the-definition-of-interconnection-cord","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/fr\/clause-3-how-to-understand-the-definition-of-interconnection-cord\/","title":{"rendered":"Clause 3 \u2013 Comment comprendre la d\u00e9finition de \u00ab\u00a0cordon d&#8217;interconnexion\u00a0\u00bb"},"content":{"rendered":"cordon d&#8217;interconnexion\uff1a cordon flexible externe entre deux parties d&#8217;un appareil, fourni dans le cadre d&#8217;un appareil complet \u00e0 des fins autres que le raccordement au secteur<br>Note 1 \u00e0 l\u2019article : Dans les appareils fonctionnant sur batterie, si la batterie est plac\u00e9e dans un bo\u00eetier s\u00e9par\u00e9, le c\u00e2ble flexible ou le cordon flexible reliant le bo\u00eetier \u00e0 l&#8217;appareil est consid\u00e9r\u00e9 comme un cordon d&#8217;interconnexion.<br>\n<br>\nLes cordons d&#8217;interconnexion ne sont pas connect\u00e9s \u00e0 l&#8217;alimentation principale. Ils sont situ\u00e9s entre deux parties d&#8217;un appareil. Les cordons peuvent conduire l\u2019\u00e9nergie \u00e9lectrique d\u2019une pi\u00e8ce \u00e0 l\u2019autre. La notion de cordons d&#8217;interconnexion est d\u00e9finie ici pour r\u00e9duire les dangers provoqu\u00e9s par les cordons d&#8217;interconnexion. Les normes 25.23 et 25.24 fournissent des exigences relatives aux cordons d&#8217;interconnexion. Du point de vue des exigences de la norme, la norme prend principalement en compte les cordons externes de l&#8217;appareil, les tractions pouvant survenir lors de l&#8217;utilisation et d&#8217;autres conditions d&#8217;utilisation similaires auxquelles les cordons d&#8217;alimentation peuvent r\u00e9sister. Par cons\u00e9quent, la plupart des cordons accessibles de l\u2019ext\u00e9rieur autres que les cordons d\u2019alimentation peuvent \u00eatre consid\u00e9r\u00e9s comme des cordons d\u2019interconnexion. La note 1 est un exemple typique.<br>\n<br>\nLes climatiseurs split ont g\u00e9n\u00e9ralement une partie int\u00e9rieure ou ext\u00e9rieure s\u00e9par\u00e9e qui est directement connect\u00e9e \u00e0 l&#8217;alimentation \u00e9lectrique, et l&#8217;autre partie compl\u00e8te la transmission de l&#8217;\u00e9nergie via un cordon d&#8217;interconnexion. Par cons\u00e9quent, les cordons int\u00e9rieurs et ext\u00e9rieurs utilis\u00e9s par les climatiseurs split sont consid\u00e9r\u00e9s comme des cordons d&#8217;interconnexion.<br>\n<br>\nLe produit illustr\u00e9 dans la figure ci-dessous est un ventilateur avec fonction d&#8217;atomisation (soufflant de l&#8217;eau sous forme de brouillard). Le fil de liaison entre la partie sup\u00e9rieure de la t\u00eate du ventilateur et la partie inf\u00e9rieure du r\u00e9servoir d&#8217;eau blanche peut \u00eatre consid\u00e9r\u00e9 comme un cordon d&#8217;interconnexion.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/wall-mounted-mist-fan.jpg\" alt=\"\" class=\"wp-image-269\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/wall-mounted-mist-fan.jpg 800w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/wall-mounted-mist-fan-300x300.jpg 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/wall-mounted-mist-fan-150x150.jpg 150w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/wall-mounted-mist-fan-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><br>\n<\/figure><br>\nComme le montre la figure ci-dessous, il s&#8217;agit d&#8217;un fil typique entre le circuit imprim\u00e9 d&#8217;affichage et le circuit imprim\u00e9 de commande principal d&#8217;une unit\u00e9 int\u00e9rieure de climatiseur mural divis\u00e9. Bien que le cordon puisse \u00eatre touch\u00e9 en ouvrant manuellement le couvercle sup\u00e9rieur, le cordon se trouve \u00e0 l&#8217;int\u00e9rieur de l&#8217;appareil lors d&#8217;une utilisation normale et n&#8217;est donc pas consid\u00e9r\u00e9 comme un cordon d&#8217;interconnexion. Cependant, le responsable doit toujours r\u00e9pondre aux exigences de la clause 22.8.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"495\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/floor-standing-mist-fan.jpg\" alt=\"\" class=\"wp-image-270\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/floor-standing-mist-fan.jpg 240w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/floor-standing-mist-fan-145x300.jpg 145w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><br>\n<\/figure><br>\nVoici un cas plus controvers\u00e9, celui du cordon \u00e0 l\u2019int\u00e9rieur du compartiment du compresseur \u00e0 l\u2019arri\u00e8re du r\u00e9frig\u00e9rateur. Les cordons dans le cercle rouge dans la figure ci-dessous sont consid\u00e9r\u00e9s comme des cordons d&#8217;interconnexion par la plupart des organismes de test ou laboratoires tiers.<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/split-AC-indoor-unit-leads-for-display-PCB-board-768x1024.jpg\" alt=\"\" class=\"wp-image-277\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/split-AC-indoor-unit-leads-for-display-PCB-board-768x1024.jpg 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/split-AC-indoor-unit-leads-for-display-PCB-board-225x300.jpg 225w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/split-AC-indoor-unit-leads-for-display-PCB-board.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><br>\n<\/figure><br>\nMon opinion personnelle est que le cordon dans le compartiment du compresseur du r\u00e9frig\u00e9rateur n&#8217;est pas un cordon d&#8217;interconnexion. Nous pouvons d\u00e9duire l&#8217;intention de la norme \u00e0 partir des exigences de 25.23 et 25.24. La norme exige que le cordon d&#8217;interconnexion r\u00e9ponde aux exigences du cordon d&#8217;alimentation. Le cordon d&#8217;alimentation peut \u00eatre tir\u00e9, le test de 25h15 est donc requis. Le cordon d&#8217;alimentation se caract\u00e9rise par \u00eatre externe \u00e0 l&#8217;appareil et peut \u00eatre touch\u00e9 et tir\u00e9. Il est peu probable que le cordon du r\u00e9frig\u00e9rateur dont nous parlons ici soit touch\u00e9 et ne soit fondamentalement pas tir\u00e9.<br>\n<figure class=\"wp-block-image size-large is-resized\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Compressor-compartment-on-the-back-of-the-refrigerator-1024x768.jpg\" alt=\"\" class=\"wp-image-279\" style=\"width:768px;height:auto\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Compressor-compartment-on-the-back-of-the-refrigerator-1024x768.jpg 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Compressor-compartment-on-the-back-of-the-refrigerator-300x225.jpg 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Compressor-compartment-on-the-back-of-the-refrigerator-768x576.jpg 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Compressor-compartment-on-the-back-of-the-refrigerator-1536x1152.jpg 1536w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Compressor-compartment-on-the-back-of-the-refrigerator-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure><br>\nUn appareil est aliment\u00e9 par un jeu de cordons et est compos\u00e9 de la partie A et de la partie B, la partie B \u00e9tant portative et connect\u00e9e \u00e0 la partie A par un cordon d&#8217;interconnexion. Ces informations proviennent de la d\u00e9cision CTL OD-5002-F3:2021.<br>\n<br>\nAn appliance is supplied by a cord set and is composed of Part A and Part B, where Part B is handheld and connected to Part A by an <a href=\"\/index.php\/clause-3-how-to-understand-the-definition-of-interconnection-cord\/\" target=\"_blank\"><strong>interconnection cord<\/strong><\/a>. This information come from CTL <a href=\"https:\/\/decisions.iecee.org\/iecee\/SearchCMC.nsf\/de_h.xsp?v=all\/\" target=\"_blank\"><strong>decision<\/strong><\/a> OD-5002-F3:2021.<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"183\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Class-II-appliance-with-Class-III-construction-OD-5002-f3-1024x183.png\" alt=\"\" class=\"wp-image-377\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Class-II-appliance-with-Class-III-construction-OD-5002-f3-1024x183.png 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Class-II-appliance-with-Class-III-construction-OD-5002-f3-300x54.png 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Class-II-appliance-with-Class-III-construction-OD-5002-f3-768x137.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Class-II-appliance-with-Class-III-construction-OD-5002-f3-1536x275.png 1536w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Class-II-appliance-with-Class-III-construction-OD-5002-f3-2048x366.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>cordon d&#8217;interconnexion\uff1a cordon flexible externe entre deux parties d&#8217;un appareil, fourni dans le cadre d&#8217;un appareil complet \u00e0 des fins autres que le raccordement au secteurNote 1 \u00e0 l\u2019article : Dans les appareils fonctionnant sur batterie, si la batterie est plac\u00e9e dans un bo\u00eetier s\u00e9par\u00e9, le c\u00e2ble flexible ou le cordon flexible reliant le bo\u00eetier&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[69],"class_list":["post-266","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-external-flexible-cord-between-two-parts-of-an-appliance-provided-as-part-of-a-complete-appliance-for-purposes-other-than-connection-to-the-supply-mains"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"fr","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":false,"content":false,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":false,"content":false,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":false,"content":false,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=266"}],"version-history":[{"count":31,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/266\/revisions"}],"predecessor-version":[{"id":1830,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/266\/revisions\/1830"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}