{"id":313,"date":"2024-08-03T05:32:54","date_gmt":"2024-08-03T03:32:54","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=313"},"modified":"2025-09-27T17:50:24","modified_gmt":"2025-09-27T15:50:24","slug":"clause-3-how-to-understand-the-definition-of-type-x-type-y-type-z-attachment","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/fr\/clause-3-how-to-understand-the-definition-of-type-x-type-y-type-z-attachment\/","title":{"rendered":"Clause 3 \u2013 Comment comprendre la d\u00e9finition de \u00ab pi\u00e8ce jointe de type X, de type Y, de type Z \u00bb"},"content":{"rendered":"Le type de raccordement est d\u00e9fini par le fabricant de l&#8217;appareil. D\u2019une mani\u00e8re g\u00e9n\u00e9rale, il est rare de le d\u00e9finir comme Type X, car cela entra\u00eenerait des risques inutiles pour le fabricant. Il est commun\u00e9ment d\u00e9fini comme type Y. Bien entendu, si le cordon d&#8217;alimentation est moul\u00e9, il est g\u00e9n\u00e9ralement d\u00e9fini comme type Z. La figure suivante r\u00e9pertorie les sch\u00e9mas de connexion des trois types de fixation.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"309\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ.png\" alt=\"\" class=\"wp-image-314\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ.png 355w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ-300x261.png 300w\" sizes=\"auto, (max-width: 355px) 100vw, 355px\" \/><br>\n<\/figure><br>\nFixation de type X\u00a0: le raccordement du cordon d&#8217;alimentation s&#8217;effectue dans un espace sp\u00e9cialement am\u00e9nag\u00e9 dans l&#8217;appareil. Par cons\u00e9quent, lors du remplacement du cordon d&#8217;alimentation, aucune autre pi\u00e8ce que le bornier et le fil interne ne sera touch\u00e9e. Les vis qui fixent le cordon d&#8217;alimentation sont des vis ordinaires \u00e0 t\u00eate cruciforme ou plate. Le remplacement du cordon d&#8217;alimentation s&#8217;effectue dans une plage contr\u00f4lable. Le cordon d&#8217;alimentation remplac\u00e9 par les utilisateurs ordinaires est relativement simple et utilisable.<br>\n<br>\nFixation de type Y\u00a0: lors du remplacement du cordon d&#8217;alimentation, il est g\u00e9n\u00e9ralement n\u00e9cessaire d&#8217;ouvrir le bo\u00eetier structurel de l&#8217;appareil, et ces bo\u00eetiers sont fix\u00e9s par des vis sp\u00e9ciales, telles que des vis hexagonales. Apr\u00e8s avoir ouvert le bo\u00eetier structurel de l&#8217;appareil, le remplacement peut toucher les pi\u00e8ces mobiles dangereuses ou d&#8217;autres pi\u00e8ces sous tension \u00e0 l&#8217;int\u00e9rieur de l&#8217;appareil. Dans ce cas, il est plus s\u00fbr de d\u00e9finir la connexion comme une fixation de type Y et de demander \u00e0 des professionnels de remplacer le cordon d&#8217;alimentation. Habituellement, les vis de fixation sont des vis ordinaires qui peuvent \u00eatre actionn\u00e9es par des utilisateurs ordinaires, mais si des pi\u00e8ces dangereuses peuvent \u00eatre touch\u00e9es lors du remplacement du cordon d&#8217;alimentation, cela est g\u00e9n\u00e9ralement d\u00e9fini comme une fixation de type Y.<br>\n<br>\nPi\u00e8ce jointe de type Z, voir l&#8217;explication et les exemples en 3.2.6.<br>","protected":false},"excerpt":{"rendered":"<p>Le type de raccordement est d\u00e9fini par le fabricant de l&#8217;appareil. D\u2019une mani\u00e8re g\u00e9n\u00e9rale, il est rare de le d\u00e9finir comme Type X, car cela entra\u00eenerait des risques inutiles pour le fabricant. Il est commun\u00e9ment d\u00e9fini comme type Y. Bien entendu, si le cordon d&#8217;alimentation est moul\u00e9, il est g\u00e9n\u00e9ralement d\u00e9fini comme type Z. La&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[70,71,72,73],"class_list":["post-313","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-flexible-cord-for-supply-purposes-that-is-fixed-to-the-appliance","tag-method-of-attachment-of-the-supply-cord-such-that-it-can-easily-be-replaced","tag-method-of-attachment-of-the-supply-cord-such-that-any-replacement-is-intended-to-be-made-by-the-manufacturer-its-service-agent-or-similar-qualified-person","tag-method-of-attachment-of-the-supply-cord-such-that-it-cannot-be-replaced-without-breaking-or-destroying-the-appliance"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"fr","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":22,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/313\/revisions\/1948"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}