{"id":597,"date":"2024-08-27T18:36:20","date_gmt":"2024-08-27T16:36:20","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=597"},"modified":"2025-09-27T17:50:23","modified_gmt":"2025-09-27T15:50:23","slug":"clause-3-how-to-understand-the-definition-of-clearance","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/fr\/clause-3-how-to-understand-the-definition-of-clearance\/","title":{"rendered":"Clause 3 \u2013 Comment comprendre la d\u00e9finition de \u00ab autorisation \u00bb"},"content":{"rendered":"espace libre : distance la plus courte dans l&#8217;air entre deux pi\u00e8ces conductrices ou entre une pi\u00e8ce conductrice et le<br>surface accessible.<br>\n<br>\nLe d\u00e9douanement est un concept tr\u00e8s important. Pour comprendre le d\u00e9gagement, il faut r\u00e9p\u00e9ter qu\u2019aucune substance n\u2019est compl\u00e8tement isol\u00e9e et que l\u2019air peut \u00e9galement conduire l\u2019\u00e9lectricit\u00e9. Lorsque la tension est tr\u00e8s \u00e9lev\u00e9e, le courant est conduit dans l\u2019air. La foudre lors d\u2019un orage est un exemple typique de foudre se propageant dans l\u2019air. La tension de la foudre est tr\u00e8s \u00e9lev\u00e9e, elle peut donc traverser une tr\u00e8s longue section d\u2019air, rendant cette section d\u2019air conductrice. Dans les appareils \u00e9lectrom\u00e9nagers, bien que la tension soit tr\u00e8s basse, il y a beaucoup d&#8217;air dans le produit et le courant sera \u00e9galement conduit dans l&#8217;air. \u00c0 mesure que la tension augmente, la distance sur laquelle la tension peut traverser l\u2019air deviendra \u00e9galement plus longue. Cela donne naissance \u00e0 la notion de d\u00e9gagement.<br>Pour une explication d\u00e9taill\u00e9e du d\u00e9gagement, veuillez vous r\u00e9f\u00e9rer \u00e0 la norme CEI 60664-1 (Coordination de l&#8217;isolation des \u00e9quipements dans les syst\u00e8mes basse tension \u2013 Partie 1 : Principes, exigences et tests).<br>\n<br>\nJe pense que les images suivantes peuvent bien expliquer le chemin du d\u00e9gagement \u00e9lectrique.<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"1024\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/clearance-and-creepage-1-636x1024.png\" alt=\"\" class=\"wp-image-2114\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/clearance-and-creepage-1-636x1024.png 636w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/clearance-and-creepage-1-186x300.png 186w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/clearance-and-creepage-1-768x1236.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/09\/clearance-and-creepage-1.png 840w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><br>\n<\/figure><br>\nUn espace peut \u00eatre form\u00e9 entre deux \u00e9lectrodes de tensions diff\u00e9rentes, ou entre une pi\u00e8ce sous tension et la main d&#8217;un utilisateur de produit \u00e9lectrique. Il vous suffit d&#8217;imaginer les deux \u00e9lectrodes de l&#8217;image ci-dessus comme d&#8217;autres objets. <br>Lorsque nous avons expliqu\u00e9 l&#8217;isolation de base et l&#8217;isolation fonctionnelle, nous avons donn\u00e9 de vraies photos pour expliquer les exemples de d\u00e9gagement et de ligne de fuite.<br>\n<br>\nFigure 11 \u2013 Exemples de d\u00e9gagements dans la norme CEI 60335-1 donne un exemple simple. Sur la base de ce chiffre, nous pouvons r\u00e9fl\u00e9chir aux caract\u00e9ristiques de base de l&#8217;appareil de classe II, de la construction de classe II, de l&#8217;appareil de classe I et de la construction de classe I.<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"702\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/Figure-11-\u2013-Examples-of-clearances-1024x702.png\" alt=\"\" class=\"wp-image-2195\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/Figure-11-\u2013-Examples-of-clearances-1024x702.png 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/Figure-11-\u2013-Examples-of-clearances-300x206.png 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/Figure-11-\u2013-Examples-of-clearances-768x526.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/Figure-11-\u2013-Examples-of-clearances.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure><br>\nCl\u00e9<br>1 pi\u00e8ce m\u00e9tallique d\u00e9terr\u00e9e accessible<br>2 enceinte<br>3 partie m\u00e9tallique mise \u00e0 la terre accessible<br>4 pi\u00e8ce m\u00e9tallique d\u00e9terr\u00e9e inaccessible<br>Les parties actives L1 et L2 sont s\u00e9par\u00e9es l&#8217;une de l&#8217;autre et partiellement entour\u00e9es d&#8217;une enceinte en plastique contenant des ouvertures, partiellement par air et sont en contact avec une isolation solide. Un morceau de m\u00e9tal inaccessible est incorpor\u00e9 \u00e0 l\u2019int\u00e9rieur de la construction. Il y a deux capots m\u00e9talliques dont un mis \u00e0 la terre.<br>                               Type d&#8217;isolation D\u00e9gagement                            <br>                               Isolation de base L1A<br>                                                                                                  L1D<br>                                                                                                  L2F<br>                               Isolation fonctionnelle L1L2<br>                               Isolation suppl\u00e9mentaire DE<br>                                                                                                 FG<br>                               Isolation renforc\u00e9e L1K<br>                                                                                                 L1J<br>                                                                                                 L2I<br>                                                                                                 L1C<br><em>REMARQUE Si les d\u00e9gagements L1D ou L2F r\u00e9pondent aux exigences de d\u00e9gagement pour l&#8217;isolation renforc\u00e9e, les d\u00e9gagements DE ou FG de l&#8217;isolation suppl\u00e9mentaire ne sont pas mesur\u00e9s.<\/em>","protected":false},"excerpt":{"rendered":"<p>espace libre : distance la plus courte dans l&#8217;air entre deux pi\u00e8ces conductrices ou entre une pi\u00e8ce conductrice et lesurface accessible. Le d\u00e9douanement est un concept tr\u00e8s important. Pour comprendre le d\u00e9gagement, il faut r\u00e9p\u00e9ter qu\u2019aucune substance n\u2019est compl\u00e8tement isol\u00e9e et que l\u2019air peut \u00e9galement conduire l\u2019\u00e9lectricit\u00e9. Lorsque la tension est tr\u00e8s \u00e9lev\u00e9e, le courant&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[74,82,166,83,84,87,78,105],"class_list":["post-597","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-insulation-applied-to-live-parts-to-provide-basic-protection-against-electric-shock","tag-appliance-in-which-protection-against-electric-shock-does-not-rely-on-basic-insulation-only-but-which-includes-an-additional-safety-precaution-in-that-conductive-accessible-parts-are-connected-to-the","tag-class-i-construction","tag-appliance-in-which-protection-against-electric-shock-does-not-rely-on-basic-insulation-only-but-in-which-additional-safety-precautions-are-provided-such-as-double-insulation-or-reinforced-insulation","tag-part-of-an-appliance-for-which-protection-against-electric-shock-relies-upon-double-insulation-or-reinforced-insulation","tag-shortest-distance-in-air-between-two-conductive-parts-or-between-a-conductive-part-and-the-accessible-surface","tag-insulation-between-conductive-parts-of-different-potential-which-is-necessary-only-for-the-proper-functioning-of-the-appliance","tag-conductor-or-conductive-part-intended-to-be-energized-in-normal-use-including-a-neutral-conductor-but-by-convention-not-a-pen-conductor"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"fr","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=597"}],"version-history":[{"count":78,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/597\/revisions"}],"predecessor-version":[{"id":2235,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/posts\/597\/revisions\/2235"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}