{"id":313,"date":"2024-08-03T05:32:54","date_gmt":"2024-08-03T03:32:54","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=313"},"modified":"2025-09-27T17:50:24","modified_gmt":"2025-09-27T15:50:24","slug":"clause-3-how-to-understand-the-definition-of-type-x-type-y-type-z-attachment","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/it\/clause-3-how-to-understand-the-definition-of-type-x-type-y-type-z-attachment\/","title":{"rendered":"Clausola 3 \u2013 Come comprendere la definizione di \u201cattacco tipo X, tipo Y, tipo Z\u201d"},"content":{"rendered":"Il tipo di collegamento \u00e8 definito dal produttore dell&#8217;apparecchio. In generale, \u00e8 raro definirlo Tipo X, perch\u00e9 ci\u00f2 comporterebbe rischi inutili per il produttore. Comunemente viene definito Tipo Y. Naturalmente, se il cavo di alimentazione \u00e8 in fusione, generalmente viene definito Tipo Z. Nella figura seguente sono elencati gli schemi di collegamento delle tre tipologie di attacco.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"309\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ.png\" alt=\"\" class=\"wp-image-314\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ.png 355w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/type-XYZ-300x261.png 300w\" sizes=\"auto, (max-width: 355px) 100vw, 355px\" \/><br>\n<\/figure><br>\nAttacco tipo X: il collegamento del cavo di alimentazione si completa in uno spazio appositamente predisposto nell&#8217;apparecchio. Pertanto, quando si sostituisce il cavo di alimentazione, nessun&#8217;altra parte verr\u00e0 toccata tranne la morsettiera e il filo interno. Le viti che fissano il cavo di alimentazione sono normali viti a croce o a testa piatta. La sostituzione del cavo di alimentazione viene effettuata entro un intervallo controllabile. Il cavo di alimentazione sostituito dagli utenti ordinari \u00e8 relativamente semplice e utilizzabile.<br>\n<br>\nAttacco tipo Y: quando si sostituisce il cavo di alimentazione, generalmente \u00e8 necessario aprire l&#8217;alloggiamento strutturale dell&#8217;apparecchio, e tali alloggiamenti sono fissati mediante viti speciali, ad esempio viti esagonali. Dopo aver aperto l&#8217;involucro strutturale dell&#8217;apparecchio, il sostituto pu\u00f2 toccare parti mobili pericolose o altre parti sotto tensione all&#8217;interno dell&#8217;apparecchio. In questo caso \u00e8 pi\u00f9 sicuro definire il collegamento come attacco di Tipo Y e richiedere a professionisti di sostituire il cavo di alimentazione. Solitamente, le viti di fissaggio sono viti normali che possono essere azionate da utenti comuni, ma se durante la sostituzione del cavo di alimentazione si possono toccare parti pericolose, si parla generalmente di attacco di Tipo Y.<br>\n<br>\nAllegato tipo Z, vedere spiegazione ed esempi in 3.2.6.<br>","protected":false},"excerpt":{"rendered":"<p>Il tipo di collegamento \u00e8 definito dal produttore dell&#8217;apparecchio. In generale, \u00e8 raro definirlo Tipo X, perch\u00e9 ci\u00f2 comporterebbe rischi inutili per il produttore. Comunemente viene definito Tipo Y. Naturalmente, se il cavo di alimentazione \u00e8 in fusione, generalmente viene definito Tipo Z. Nella figura seguente sono elencati gli schemi di collegamento delle tre tipologie&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[70,71,72,73],"class_list":["post-313","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-flexible-cord-for-supply-purposes-that-is-fixed-to-the-appliance","tag-method-of-attachment-of-the-supply-cord-such-that-it-can-easily-be-replaced","tag-method-of-attachment-of-the-supply-cord-such-that-any-replacement-is-intended-to-be-made-by-the-manufacturer-its-service-agent-or-similar-qualified-person","tag-method-of-attachment-of-the-supply-cord-such-that-it-cannot-be-replaced-without-breaking-or-destroying-the-appliance"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"it","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":22,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/313\/revisions\/1948"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}