{"id":577,"date":"2024-08-17T17:18:28","date_gmt":"2024-08-17T15:18:28","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=577"},"modified":"2025-09-27T17:50:23","modified_gmt":"2025-09-27T15:50:23","slug":"clause-3-how-to-understand-the-definition-of-class-iii-appliance","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/it\/clause-3-how-to-understand-the-definition-of-class-iii-appliance\/","title":{"rendered":"Clausola 3 \u2013 Come comprendere la definizione di \u201capparecchio di classe III\u201d"},"content":{"rendered":"apparecchio di classe III: apparecchio in cui la protezione contro la scossa elettrica \u00e8 affidata all&#8217;alimentazione a bassissima tensione di sicurezza e in cui non vengono generate tensioni superiori a quelle della bassissima tensione di sicurezza.<br><em>NOTA Potrebbe essere necessario un isolamento di base in aggiunta alla fornitura a SELV. Fare riferimento a 8.1.4.<\/em><br>\nPer capirlo, \u00e8 necessario prima capire cos&#8217;\u00e8 la bassissima tensione di sicurezza (SELV). Fare riferimento alla definizione e alla spiegazione di SELV. Questo tipo di prodotto \u00e8 generalmente alimentato tramite un adattatore, USB o un alimentatore a bassa tensione in un&#8217;auto. Quando questo tipo di prodotto viene venduto, non sar\u00e0 dotato di un dispositivo che converte l&#8217;alimentazione CA 100-240 V nella bassa tensione necessaria, perch\u00e9 se \u00e8 dotato di un dispositivo di conversione, come un adattatore, allora l&#8217;adattatore e il l&#8217;apparecchio forma un insieme e il livello di protezione dell&#8217;insieme \u00e8 determinato dall&#8217;adattatore. L&#8217;adattatore \u00e8 solitamente una costruzione di classe II, quindi l&#8217;adattatore e l&#8217;apparecchio sono definiti come apparecchi di classe II. Poich\u00e9 la tensione di alimentazione di questo tipo di apparecchio \u00e8 relativamente bassa, a volte porta all&#8217;impossibilit\u00e0 di completare alcune funzioni elettriche specifiche, quindi \u00e8 necessario utilizzare un circuito boost per aumentare la tensione per ottenere alcune funzioni speciali dell&#8217;apparecchio. Ad esempio, la funzione di un generatore di ioni negativi richiede un&#8217;operazione di boost. Questo tipo di apparecchio con un generatore di ioni negativi simile o un funzionamento boost (valore di tensione superiore a SELV) non pu\u00f2 essere determinato come apparecchio di Classe III.<br>\n<br>\nLa parola &#8220;sicurezza&#8221; \u00e8 inclusa nelle quattro parole &#8220;bassa tensione di sicurezza&#8221;, ma ci\u00f2 non significa che SELV sia sicuro e non \u00e8 necessariamente sicuro toccarlo direttamente. \u00c8 possibile toccare direttamente solo i circuiti di sicurezza a bassissima tensione che soddisfano i requisiti della norma 8.1.4. Analizzeremo e spiegheremo specificamente questo aspetto durante l&#8217;analisi della clausola 8.1.4.<br>\n<br>\nIl ventilatore rappresentato nella figura seguente pu\u00f2 essere definito un apparecchio di classe III. Tuttavia, questo ventilatore ha due orecchie, il che lo rende non conforme alla clausola 22.44. Spiegheremo i dettagli pi\u00f9 tardi.<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"1024\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/class-III-appliance-1-575x1024.jpg\" alt=\"\" class=\"wp-image-579\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/class-III-appliance-1-575x1024.jpg 575w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/class-III-appliance-1-169x300.jpg 169w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/class-III-appliance-1-768x1367.jpg 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/08\/class-III-appliance-1.jpg 860w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><br>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>apparecchio di classe III: apparecchio in cui la protezione contro la scossa elettrica \u00e8 affidata all&#8217;alimentazione a bassissima tensione di sicurezza e in cui non vengono generate tensioni superiori a quelle della bassissima tensione di sicurezza.NOTA Potrebbe essere necessario un isolamento di base in aggiunta alla fornitura a SELV. Fare riferimento a 8.1.4. Per capirlo,&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[74,83,84,85,147,90,163],"class_list":["post-577","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-insulation-applied-to-live-parts-to-provide-basic-protection-against-electric-shock","tag-appliance-in-which-protection-against-electric-shock-does-not-rely-on-basic-insulation-only-but-in-which-additional-safety-precautions-are-provided-such-as-double-insulation-or-reinforced-insulation","tag-part-of-an-appliance-for-which-protection-against-electric-shock-relies-upon-double-insulation-or-reinforced-insulation","tag-appliance-in-which-protection-against-electric-shock-relies-on-supply-at-safety-extra-low-voltage-and-in-which-voltages-higher-than-those-of-safety-extra-low-voltage-are-not-generated","tag-protection-against-electric-shock","tag-voltage-not-exceeding-42-v-between-conductors-and-between-conductors-and-earth-or-functional-earth-the-no-load-voltage-not-exceeding-50-v","tag-selv"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"it","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":30,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"predecessor-version":[{"id":1994,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/577\/revisions\/1994"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}