{"id":99,"date":"2024-07-04T17:09:45","date_gmt":"2024-07-04T15:09:45","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=99"},"modified":"2025-09-27T17:50:26","modified_gmt":"2025-09-27T15:50:26","slug":"clause-1scope-note-1-interpretation-of-the-first-paragraphs-note","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/it\/clause-1scope-note-1-interpretation-of-the-first-paragraphs-note\/","title":{"rendered":"Clausola 1(Ambito di applicazione)-Nota 1 Interpretazione della nota del primo paragrafo"},"content":{"rendered":"Nota 1 come di seguito:<br>NOTA 1 Apparecchi a batteria e altri apparecchi a corrente continua gli apparecchi forniti rientrano nell&#8217;ambito di applicazione di questa norma. Gli apparecchi a doppia alimentazione, alimentati dalla rete elettrica o alimentati a batteria, sono considerati apparecchi alimentati a batteria se utilizzati in modalit\u00e0 batteria.<br>\n<br>\nGli attuatori della norma potrebbero pensare che i requisiti di questa norma possano essere disattesi per quegli apparecchi alimentati a batteria dove non vi \u00e8 rischio di scossa elettrica a causa della bassa tensione della batteria stessa. Tuttavia, dalla situazione reale, questo non \u00e8 il caso. Sebbene questo standard si concentri sulla sicurezza elettrica del prodotto, si concentra anche sulla presenza di rischi meccanici, termici, di incendio, chimici o tossici nel prodotto. Anche se non sono presenti danni elettrici, nel prodotto potrebbero essere presenti altri elementi pericolosi che devono comunque essere valutati utilizzando questo standard. Inoltre, alcuni prodotti alimentati a batteria, anche se la tensione della batteria stessa \u00e8 molto bassa, all&#8217;interno del prodotto sar\u00e0 presente un circuito di potenziamento e la tensione potenziata sar\u00e0 comunque dannosa per il corpo umano, che deve comunque essere considerato come un requisito di sicurezza.<br>\n<figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/negative-ion-air-purifiercar-desktop-portable.jpg\" alt=\"\" class=\"wp-image-103\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/negative-ion-air-purifiercar-desktop-portable.jpg 1000w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/negative-ion-air-purifiercar-desktop-portable-300x300.jpg 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/negative-ion-air-purifiercar-desktop-portable-150x150.jpg 150w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/negative-ion-air-purifiercar-desktop-portable-768x768.jpg 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/negative-ion-air-purifiercar-desktop-portable-60x60.jpg 60w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><br>\n<\/figure><br>Ad esempio, una ventola portatile alimentata da una batteria ricaricabile ha le pale della ventola esposte che possono essere raggiunte direttamente con la mano. Sebbene le tensioni operative sia della batteria che del motore della ventola siano basse e la pala della ventola sia morbida; \u00e8 comunque necessario verificare se qualche parte della tensione di funzionamento interna dell&#8217;apparecchio \u00e8 superiore a quella della batteria e, allo stesso tempo, la durezza della pala del ventilatore \u00e8 inferiore al valore limite specificato nella norma.<br>\n<figure class=\"wp-block-image size-large is-resized\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1-1024x1024.png\" alt=\"\" class=\"wp-image-102\" style=\"width:564px;height:auto\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1-1024x1024.png 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1-300x300.png 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1-150x150.png 150w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1-768x768.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1-60x60.png 60w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/handheld-fan-powered-by-a-rechargeable-battery-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Nota 1 come di seguito:NOTA 1 Apparecchi a batteria e altri apparecchi a corrente continua gli apparecchi forniti rientrano nell&#8217;ambito di applicazione di questa norma. Gli apparecchi a doppia alimentazione, alimentati dalla rete elettrica o alimentati a batteria, sono considerati apparecchi alimentati a batteria se utilizzati in modalit\u00e0 batteria. Gli attuatori della norma potrebbero pensare&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[3],"tags":[150],"class_list":["post-99","post","type-post","status-publish","format-standard","hentry","category-scope","tag-general-information"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"it","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":29,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/99\/revisions"}],"predecessor-version":[{"id":1741,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/posts\/99\/revisions\/1741"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/categories?post=99"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/it\/wp-json\/wp\/v2\/tags?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}