{"id":101,"count":1,"description":"","link":"https:\/\/gezhi-tech.com\/ja\/tag\/appliance-deriving-its-energy-from-batteries-enabling-the-appliance-to-perform-its-intended-function-without-a-mains-supply-connection\/","name":"battery-operated appliance","slug":"appliance-deriving-its-energy-from-batteries-enabling-the-appliance-to-perform-its-intended-function-without-a-mains-supply-connection","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/ja\/wp-json\/wp\/v2\/tags\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gezhi-tech.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gezhi-tech.com\/ja\/wp-json\/wp\/v2\/posts?tags=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}