{"id":140,"date":"2024-07-11T11:22:15","date_gmt":"2024-07-11T09:22:15","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=140"},"modified":"2025-10-05T09:13:43","modified_gmt":"2025-10-05T07:13:43","slug":"clause-3-how-to-understand-the-definition-of-the-noun-rated-voltage-range","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/pt\/clause-3-how-to-understand-the-definition-of-the-noun-rated-voltage-range\/","title":{"rendered":"Cl\u00e1usula 3 \u2013 Como entender a defini\u00e7\u00e3o de \u201cfaixa de tens\u00e3o nominal\u201d"},"content":{"rendered":"<strong>faixa de tens\u00e3o nominal<\/strong>:<br>faixa de tens\u00e3o atribu\u00edda ao aparelho pelo fabricante, expressa pelos seus limites inferior e superior.<br>\n<br>\nEsta defini\u00e7\u00e3o \u00e9 uma extens\u00e3o da defini\u00e7\u00e3o de <strong>tens\u00e3o nominal<\/strong>. \u00c9 uma tens\u00e3o nominal na forma de uma faixa com valores superiores e inferiores. Freq\u00fcentemente, quando um fabricante projeta um produto com um grande n\u00famero de pa\u00edses de mercado-alvo para o mesmo produto, \u00e9 necess\u00e1rio considerar a especifica\u00e7\u00e3o da tens\u00e3o nominal na forma de uma faixa de <strong>tens\u00e3o nominal<\/strong>. Desta forma, uma \u00fanica faixa de tens\u00e3o nominal pode ser usada para cobrir diferentes tens\u00f5es de servi\u00e7os p\u00fablicos em diferentes pa\u00edses. De modo geral, a maioria dos fabricantes opta por especificar uma gama de <strong>tens\u00e3o nominal<\/strong>, mas raramente uma tens\u00e3o nominal definida.<br>\n<br>\nPor exemplo, um produto projetado para o mercado-alvo para todo o mercado europeu de todos os estados membros da UE, a maioria dos estados membros da UE da tens\u00e3o da rede el\u00e9trica \u00e9 AC 230V, mas h\u00e1 alguns pa\u00edses que \u00e9 AC 240V, mesmo que apenas uma disposi\u00e7\u00e3o separada da tens\u00e3o nominal de AC230V ou AC240V, ent\u00e3o, este produto n\u00e3o pode ser usado na rede el\u00e9trica, a tens\u00e3o \u00e9 diferente da tens\u00e3o nominal do pa\u00eds. Diante desta situa\u00e7\u00e3o, podemos especificar a tens\u00e3o nominal na forma de uma faixa AC220-240V, que abrange AC220V e AC230V e AC240V, para que os produtos correspondentes possam ser utilizados em pa\u00edses com essas tr\u00eas tens\u00f5es de rede. Aqui, AC220-240V ou 220-240V~ \u00e9 uma forma mais comum; tamb\u00e9m haver\u00e1 220-230V~ ou 380V-415V~, ou 100-240V~ (a maior parte desta situa\u00e7\u00e3o ocorre no uso de adaptadores alimentados pela tens\u00e3o de entrada nominal do adaptador) e assim por diante.<br>\n<br>\nComo a tens\u00e3o nominal do produto est\u00e1 definida em uma faixa, os requisitos de seguran\u00e7a nesta faixa de tens\u00e3o precisam ser avaliados de acordo com a norma.<br>","protected":false},"excerpt":{"rendered":"<p>faixa de tens\u00e3o nominal:faixa de tens\u00e3o atribu\u00edda ao aparelho pelo fabricante, expressa pelos seus limites inferior e superior. Esta defini\u00e7\u00e3o \u00e9 uma extens\u00e3o da defini\u00e7\u00e3o de tens\u00e3o nominal. \u00c9 uma tens\u00e3o nominal na forma de uma faixa com valores superiores e inferiores. Freq\u00fcentemente, quando um fabricante projeta um produto com um grande n\u00famero de pa\u00edses&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[56,57],"class_list":["post-140","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-voltage-assigned-to-the-appliance-by-the-manufacturer","tag-voltage-range-assigned-to-the-appliance-by-the-manufacturer-expressed-by-its-lower-and-upper-limits"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"pt","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/posts\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":28,"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/posts\/140\/revisions"}],"predecessor-version":[{"id":2839,"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/posts\/140\/revisions\/2839"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/media?parent=140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/categories?post=140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/pt\/wp-json\/wp\/v2\/tags?post=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}