{"id":218,"date":"2024-07-15T16:58:05","date_gmt":"2024-07-15T14:58:05","guid":{"rendered":"https:\/\/gezhi-tech.com\/?p=218"},"modified":"2025-09-27T17:50:25","modified_gmt":"2025-09-27T15:50:25","slug":"clause-3-how-to-understand-the-definition-of-rated-impulse-voltage","status":"publish","type":"post","link":"https:\/\/gezhi-tech.com\/ro\/clause-3-how-to-understand-the-definition-of-rated-impulse-voltage\/","title":{"rendered":"Clauza 3 \u2013 Cum s\u0103 \u00een\u021belege\u021bi defini\u021bia \u201etensiunii nominale de impuls\u201d"},"content":{"rendered":"<strong>tensiune nominal\u0103 de impuls<\/strong>: tensiune derivat\u0103 din tensiunea nominal\u0103 \u0219i categoria de supratensiune a aparatului, care caracterizeaz\u0103 capacitatea de rezisten\u021b\u0103 specificat\u0103 a izola\u021biei acestuia \u00eempotriva supratensiunilor tranzitorii.<br>\n<br>\nPentru \u00eencep\u0103tori, nu este cu adev\u0103rat necesar s\u0103 \u00een\u021belege\u021bi sensul fizic al acestei defini\u021bii. Utilizarea principal\u0103 a acestei valori de tensiune \u00een standard este de a determina valoarea limit\u0103 a jocului; cu referire la Tabelul 15, valoarea nominal\u0103 a tensiunii de impuls poate fi determinat\u0103 direct.<br>Fraza de sus a tabelului 15 indic\u0103 faptul c\u0103 \u201eAparatele sunt \u00een categoria II de supratensiune\u201d. Dac\u0103 tensiunea nominal\u0103 a produsului este AC220-240V, corespunz\u0103toare ultimului r\u00e2nd de valori din prima coloan\u0103 a tabelului 15, tensiunea nominal\u0103 a impulsului este determinat\u0103 a fi 2500V.<br>\n<br>\nTrebuie s\u0103 spun c\u0103 categoria de supratensiune (OVC) provine din standardul IEC 60664-1. tabelul de mai jos da-ne o definitie.<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"518\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-definition-1024x518.png\" alt=\"\" class=\"wp-image-222\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-definition-1024x518.png 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-definition-300x152.png 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-definition-768x388.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-definition-1536x776.png 1536w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-definition.png 1654w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure><br>\nPe de alt\u0103 parte, exist\u0103 un desen pentru a explica categoria de supratensiune (OVC).<br>\n<figure class=\"wp-block-image size-large\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-drawing-1024x577.png\" alt=\"\" class=\"wp-image-221\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-drawing-1024x577.png 1024w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-drawing-300x169.png 300w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-drawing-768x433.png 768w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-drawing-1536x865.png 1536w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/Overvoltage-category-drawing.png 1729w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br>\n<\/figure><figure class=\"wp-block-image size-full\"><br>\n<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"455\" src=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/overvoltage-category-show.png\" alt=\"\" class=\"wp-image-225\" srcset=\"https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/overvoltage-category-show.png 580w, https:\/\/gezhi-tech.com\/wp-content\/uploads\/2024\/07\/overvoltage-category-show-300x235.png 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><br>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>tensiune nominal\u0103 de impuls: tensiune derivat\u0103 din tensiunea nominal\u0103 \u0219i categoria de supratensiune a aparatului, care caracterizeaz\u0103 capacitatea de rezisten\u021b\u0103 specificat\u0103 a izola\u021biei acestuia \u00eempotriva supratensiunilor tranzitorii. Pentru \u00eencep\u0103tori, nu este cu adev\u0103rat necesar s\u0103 \u00een\u021belege\u021bi sensul fizic al acestei defini\u021bii. Utilizarea principal\u0103 a acestei valori de tensiune \u00een standard este de a determina valoarea&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5],"tags":[87,65],"class_list":["post-218","post","type-post","status-publish","format-standard","hentry","category-terms-and-definitions","tag-shortest-distance-in-air-between-two-conductive-parts-or-between-a-conductive-part-and-the-accessible-surface","tag-voltage-derived-from-the-rated-voltage-and-the-overvoltage-category-of-the-appliance-characterizing-the-specified-withstand-capability-of-its-insulation-against-transient-overvoltages"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"ro","enabled_languages":["en","es","ar","de","ja","fr","ru","th","nl","it","fa","ko","pt","hi","ro","tr","vi","id","zu"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"th":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fa":{"title":true,"content":true,"excerpt":false},"ko":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":true,"content":true,"excerpt":false},"ro":{"title":true,"content":true,"excerpt":false},"tr":{"title":true,"content":true,"excerpt":false},"vi":{"title":true,"content":true,"excerpt":false},"id":{"title":true,"content":true,"excerpt":false},"zu":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/posts\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/comments?post=218"}],"version-history":[{"count":31,"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/posts\/218\/revisions"}],"predecessor-version":[{"id":1866,"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/posts\/218\/revisions\/1866"}],"wp:attachment":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/media?parent=218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/categories?post=218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/tags?post=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}