{"id":120,"count":4,"description":"","link":"https:\/\/gezhi-tech.com\/ro\/tag\/thermal-cut-out-which-operates-only-once-and-requires-partial-or-complete-replacement\/","name":"thermal link","slug":"thermal-cut-out-which-operates-only-once-and-requires-partial-or-complete-replacement","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/tags\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gezhi-tech.com\/ro\/wp-json\/wp\/v2\/posts?tags=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}