{"id":125,"count":5,"description":"","link":"https:\/\/gezhi-tech.com\/tr\/tag\/element-intended-for-heating-consisting-mainly-of-positive-temperature-coefficient-resistors-that-are-thermally-sensitive-and-have-a-rapid-non-linear-increase-in-resistance-when-the-temperature-is-rai\/","name":"PTC heating element","slug":"element-intended-for-heating-consisting-mainly-of-positive-temperature-coefficient-resistors-that-are-thermally-sensitive-and-have-a-rapid-non-linear-increase-in-resistance-when-the-temperature-is-rai","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gezhi-tech.com\/tr\/wp-json\/wp\/v2\/tags\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezhi-tech.com\/tr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gezhi-tech.com\/tr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gezhi-tech.com\/tr\/wp-json\/wp\/v2\/posts?tags=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}